{"id":28263,"date":"2024-12-23T12:45:39","date_gmt":"2024-12-23T11:45:39","guid":{"rendered":"https:\/\/networks.imdea.org\/?p=28263"},"modified":"2024-12-23T12:50:28","modified_gmt":"2024-12-23T11:50:28","slug":"5tonic-consolidates-its-leadership-in-research-and-innovation-in-2024","status":"publish","type":"post","link":"https:\/\/networks.imdea.org\/es\/5tonic-consolida-su-liderazgo-en-investigacion-e-innovacion-en-2024\/","title":{"rendered":"5TONIC consolida su liderazgo en investigaci\u00f3n e innovaci\u00f3n en 2024"},"content":{"rendered":"<p><a href=\"https:\/\/www.5tonic.org\/\" target=\"_blank\" rel=\"noopener\">5TONIC<\/a>, el laboratorio abierto de investigaci\u00f3n e innovaci\u00f3n en tecnolog\u00edas 5G y 6G fundado por Telef\u00f3nica e IMDEA Networks, ha alcanzado varios hitos significativos en 2024 que refuerzan su posici\u00f3n como referente en el desarrollo de tecnolog\u00edas de comunicaci\u00f3n avanzadas.<\/p>\n<p>Uno de los eventos destacados ha sido el nombramiento de <strong>Cayetano Carbajo<\/strong> como presidente de 5TONIC en julio de 2024, quien aporta su vasta experiencia en el sector de las telecomunicaciones. Ha ocupado diversos cargos, incluyendo CTO en Telef\u00f3nica Alemania, CTO en Telef\u00f3nica M\u00f3viles M\u00e9xico y director de Tecnolog\u00eda Corporativa en Telef\u00f3nica. Actualmente, es director de Core, Transporte y Plataformas en la unidad Global CTIO de Telef\u00f3nica, donde lidera la transformaci\u00f3n de las redes de la compa\u00f1\u00eda.<\/p>\n<p>En febrero de 2024, 5TONIC recibi\u00f3 la visita de miembros del Ministerio de Transformaci\u00f3n Digital de Espa\u00f1a, incluyendo al secretario general de Telecomunicaciones y Servicios de Comunicaci\u00f3n Audiovisual. Durante esta visita, se realiz\u00f3 una demostraci\u00f3n de un gemelo digital con capacidades integradas de sensorizaci\u00f3n y control rob\u00f3tico a trav\u00e9s de 5G, destacando la importancia de un entorno colaborativo entre la industria y la academia en el desarrollo de tecnolog\u00edas 5G y 6G.<\/p>\n<p>En mayo de 2024,<strong> 5TONIC anunci\u00f3 su implicaci\u00f3n en proyectos clave del programa europeo SNS JU, como DESIRE 6G, Predict 6G, TrialsNet y 6G XR<\/strong>. Adem\u00e1s, participa en iniciativas del programa espa\u00f1ol UNICO I+D, incluyendo 6G-DATADRIVEN y 6G-EDGEDT. Estas colaboraciones buscan universalizar el acceso a banda ancha ultrarr\u00e1pida y extender el 5G, financiadas por el Fondo de Recuperaci\u00f3n de la Uni\u00f3n Europea \u2013 NextGenerationEU.<\/p>\n<p>El \u00e1mbito de la eficiencia energ\u00e9tica de aplicaciones verticales tambi\u00e9n ha sido otra \u00e1rea de investigaci\u00f3n. En el marco del proyecto <strong>6G DAWN<\/strong> coordinado por el CTTC, un proyecto de investigaci\u00f3n financiado por el Plan de Recuperaci\u00f3n, Transformaci\u00f3n y Resiliencia del Gobierno de Espa\u00f1a a trav\u00e9s del programa UNICO I+D 5G Ericsson y Telcaria han investigado conjuntamente mecanismos novedosos para evaluar, recomendar y aplicar configuraciones alternativas de Redes Privadas Avanzadas 5G que puedan mejorar los indicadores de eficiencia energ\u00e9tica.<\/p>\n<p>Recientemente, en diciembre de 2024, <strong>5TONIC se han firmado acuerdos de colaboraci\u00f3n con WINGS ICT Solutions y E-Lighthouse Network Solutions (ELIG)<\/strong> para apoyar proyectos adjudicados en la II Convocatoria Abierta del proyecto europeo 6G-XR. Estas colaboraciones se centran en el despliegue y validaci\u00f3n de habilitadores relacionados con el equilibrio de carga y mecanismos de seguridad y confianza en ecosistemas 6G.<\/p>\n<p>Estos logros subrayan el compromiso de 5TONIC con la investigaci\u00f3n de vanguardia y la colaboraci\u00f3n interdisciplinaria, consolidando su capacidad para albergar todos los componentes tecnol\u00f3gicos necesarios para mostrar las oportunidades que ofrecen las tecnolog\u00edas 5G y 6G en diversas industrias verticales.<\/p>","protected":false},"excerpt":{"rendered":"5TONIC, el laboratorio abierto de investigaci\u00f3n e innovaci\u00f3n en tecnolog\u00edas 5G y 6G fundado por Telef\u00f3nica e IMDEA Networks, ha alcanzado varios hitos significativos en 2024 que refuerzan su posici\u00f3n como referente en el desarrollo de tecnolog\u00edas de comunicaci\u00f3n avanzadas. Uno de los eventos destacados ha sido el nombramiento de Cayetano Carbajo como presidente de&#8230;","protected":false},"author":145,"featured_media":28264,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[468,469,1209,464,473,465],"class_list":["post-28263","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categoria","tag-5g","tag-5tonic","tag-6g","tag-imdea-networks","tag-innovation","tag-internet"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>5TONIC consolida su liderazgo en investigaci\u00f3n e innovaci\u00f3n en 2024 - IMDEA Networks<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/networks.imdea.org\/es\/5tonic-consolidates-its-leadership-in-research-and-innovation-in-2024\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"5TONIC consolida su liderazgo en investigaci\u00f3n e innovaci\u00f3n en 2024 - IMDEA Networks\" \/>\n<meta property=\"og:description\" content=\"5TONIC, el laboratorio abierto de investigaci\u00f3n e innovaci\u00f3n en tecnolog\u00edas 5G y 6G fundado por Telef\u00f3nica e IMDEA Networks, ha alcanzado varios hitos significativos en 2024 que refuerzan su posici\u00f3n como referente en el desarrollo de tecnolog\u00edas de comunicaci\u00f3n avanzadas. Uno de los eventos destacados ha sido el nombramiento de Cayetano Carbajo como presidente de...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/networks.imdea.org\/es\/5tonic-consolidates-its-leadership-in-research-and-innovation-in-2024\/\" \/>\n<meta property=\"og:site_name\" content=\"IMDEA Networks\" \/>\n<meta property=\"article:published_time\" content=\"2024-12-23T11:45:39+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-12-23T11:50:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/networks.imdea.org\/wp-content\/uploads\/2024\/12\/media-file-5g-6g-1024x576.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"576\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Marta Dorado\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Marta Dorado\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/networks.imdea.org\\\/5tonic-consolidates-its-leadership-in-research-and-innovation-in-2024\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/networks.imdea.org\\\/5tonic-consolidates-its-leadership-in-research-and-innovation-in-2024\\\/\"},\"author\":{\"name\":\"Marta Dorado\",\"@id\":\"https:\\\/\\\/networks.imdea.org\\\/#\\\/schema\\\/person\\\/1dbef87c79bf3d3657cbd4cc6c129e74\"},\"headline\":\"5TONIC consolida su liderazgo en investigaci\u00f3n e innovaci\u00f3n en 2024\",\"datePublished\":\"2024-12-23T11:45:39+00:00\",\"dateModified\":\"2024-12-23T11:50:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/networks.imdea.org\\\/5tonic-consolidates-its-leadership-in-research-and-innovation-in-2024\\\/\"},\"wordCount\":898,\"image\":{\"@id\":\"https:\\\/\\\/networks.imdea.org\\\/5tonic-consolidates-its-leadership-in-research-and-innovation-in-2024\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/networks.imdea.org\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/media-file-5g-6g.png\",\"keywords\":[\"5G\",\"5TONIC\",\"6G\",\"IMDEA Networks\",\"Innovation\",\"Internet\"],\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/networks.imdea.org\\\/es\\\/5tonic-consolidates-its-leadership-in-research-and-innovation-in-2024\\\/\",\"url\":\"https:\\\/\\\/networks.imdea.org\\\/es\\\/5tonic-consolidates-its-leadership-in-research-and-innovation-in-2024\\\/\",\"name\":\"5TONIC consolida su liderazgo en investigaci\u00f3n e innovaci\u00f3n en 2024 - IMDEA Networks\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/networks.imdea.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/networks.imdea.org\\\/es\\\/5tonic-consolidates-its-leadership-in-research-and-innovation-in-2024\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/networks.imdea.org\\\/5tonic-consolidates-its-leadership-in-research-and-innovation-in-2024\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/networks.imdea.org\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/media-file-5g-6g.png\",\"datePublished\":\"2024-12-23T11:45:39+00:00\",\"dateModified\":\"2024-12-23T11:50:28+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/networks.imdea.org\\\/#\\\/schema\\\/person\\\/1dbef87c79bf3d3657cbd4cc6c129e74\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/networks.imdea.org\\\/es\\\/5tonic-consolidates-its-leadership-in-research-and-innovation-in-2024\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[[\"https:\\\/\\\/networks.imdea.org\\\/es\\\/5tonic-consolidates-its-leadership-in-research-and-innovation-in-2024\\\/\"]]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/networks.imdea.org\\\/es\\\/5tonic-consolidates-its-leadership-in-research-and-innovation-in-2024\\\/#primaryimage\",\"url\":\"https:\\\/\\\/networks.imdea.org\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/media-file-5g-6g.png\",\"contentUrl\":\"https:\\\/\\\/networks.imdea.org\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/media-file-5g-6g.png\",\"width\":1920,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/networks.imdea.org\\\/es\\\/5tonic-consolidates-its-leadership-in-research-and-innovation-in-2024\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/networks.imdea.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"5TONIC consolidates its leadership in research and innovation in 2024\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/networks.imdea.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/networks.imdea.org\\\/es\\\/\",\"name\":\"IMDEA Networks\",\"description\":\"IMDEA Networks Multisite\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/networks.imdea.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/networks.imdea.org\\\/#\\\/schema\\\/person\\\/1dbef87c79bf3d3657cbd4cc6c129e74\",\"name\":\"Marta Dorado\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a6b289793dc91627659ec2e23425956502b6bd683dce1548a16e9ea0d40fecfb?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a6b289793dc91627659ec2e23425956502b6bd683dce1548a16e9ea0d40fecfb?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a6b289793dc91627659ec2e23425956502b6bd683dce1548a16e9ea0d40fecfb?s=96&d=mm&r=g\",\"caption\":\"Marta Dorado\"},\"url\":\"https:\\\/\\\/networks.imdea.org\\\/es\\\/author\\\/marta-doradoimdea-org\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"5TONIC consolida su liderazgo en investigaci\u00f3n e innovaci\u00f3n en 2024 - IMDEA Networks","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/networks.imdea.org\/es\/5tonic-consolidates-its-leadership-in-research-and-innovation-in-2024\/","og_locale":"es_ES","og_type":"article","og_title":"5TONIC consolida su liderazgo en investigaci\u00f3n e innovaci\u00f3n en 2024 - IMDEA Networks","og_description":"5TONIC, el laboratorio abierto de investigaci\u00f3n e innovaci\u00f3n en tecnolog\u00edas 5G y 6G fundado por Telef\u00f3nica e IMDEA Networks, ha alcanzado varios hitos significativos en 2024 que refuerzan su posici\u00f3n como referente en el desarrollo de tecnolog\u00edas de comunicaci\u00f3n avanzadas. Uno de los eventos destacados ha sido el nombramiento de Cayetano Carbajo como presidente de...","og_url":"https:\/\/networks.imdea.org\/es\/5tonic-consolidates-its-leadership-in-research-and-innovation-in-2024\/","og_site_name":"IMDEA Networks","article_published_time":"2024-12-23T11:45:39+00:00","article_modified_time":"2024-12-23T11:50:28+00:00","og_image":[{"width":1024,"height":576,"url":"https:\/\/networks.imdea.org\/wp-content\/uploads\/2024\/12\/media-file-5g-6g-1024x576.png","type":"image\/png"}],"author":"Marta Dorado","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Marta Dorado","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/networks.imdea.org\/5tonic-consolidates-its-leadership-in-research-and-innovation-in-2024\/#article","isPartOf":{"@id":"https:\/\/networks.imdea.org\/5tonic-consolidates-its-leadership-in-research-and-innovation-in-2024\/"},"author":{"name":"Marta Dorado","@id":"https:\/\/networks.imdea.org\/#\/schema\/person\/1dbef87c79bf3d3657cbd4cc6c129e74"},"headline":"5TONIC consolida su liderazgo en investigaci\u00f3n e innovaci\u00f3n en 2024","datePublished":"2024-12-23T11:45:39+00:00","dateModified":"2024-12-23T11:50:28+00:00","mainEntityOfPage":{"@id":"https:\/\/networks.imdea.org\/5tonic-consolidates-its-leadership-in-research-and-innovation-in-2024\/"},"wordCount":898,"image":{"@id":"https:\/\/networks.imdea.org\/5tonic-consolidates-its-leadership-in-research-and-innovation-in-2024\/#primaryimage"},"thumbnailUrl":"https:\/\/networks.imdea.org\/wp-content\/uploads\/2024\/12\/media-file-5g-6g.png","keywords":["5G","5TONIC","6G","IMDEA Networks","Innovation","Internet"],"articleSection":["Noticias"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/networks.imdea.org\/es\/5tonic-consolidates-its-leadership-in-research-and-innovation-in-2024\/","url":"https:\/\/networks.imdea.org\/es\/5tonic-consolidates-its-leadership-in-research-and-innovation-in-2024\/","name":"5TONIC consolida su liderazgo en investigaci\u00f3n e innovaci\u00f3n en 2024 - IMDEA Networks","isPartOf":{"@id":"https:\/\/networks.imdea.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/networks.imdea.org\/es\/5tonic-consolidates-its-leadership-in-research-and-innovation-in-2024\/#primaryimage"},"image":{"@id":"https:\/\/networks.imdea.org\/5tonic-consolidates-its-leadership-in-research-and-innovation-in-2024\/#primaryimage"},"thumbnailUrl":"https:\/\/networks.imdea.org\/wp-content\/uploads\/2024\/12\/media-file-5g-6g.png","datePublished":"2024-12-23T11:45:39+00:00","dateModified":"2024-12-23T11:50:28+00:00","author":{"@id":"https:\/\/networks.imdea.org\/#\/schema\/person\/1dbef87c79bf3d3657cbd4cc6c129e74"},"breadcrumb":{"@id":"https:\/\/networks.imdea.org\/es\/5tonic-consolidates-its-leadership-in-research-and-innovation-in-2024\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":[["https:\/\/networks.imdea.org\/es\/5tonic-consolidates-its-leadership-in-research-and-innovation-in-2024\/"]]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/networks.imdea.org\/es\/5tonic-consolidates-its-leadership-in-research-and-innovation-in-2024\/#primaryimage","url":"https:\/\/networks.imdea.org\/wp-content\/uploads\/2024\/12\/media-file-5g-6g.png","contentUrl":"https:\/\/networks.imdea.org\/wp-content\/uploads\/2024\/12\/media-file-5g-6g.png","width":1920,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/networks.imdea.org\/es\/5tonic-consolidates-its-leadership-in-research-and-innovation-in-2024\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/networks.imdea.org\/es\/"},{"@type":"ListItem","position":2,"name":"5TONIC consolidates its leadership in research and innovation in 2024"}]},{"@type":"WebSite","@id":"https:\/\/networks.imdea.org\/es\/#website","url":"https:\/\/networks.imdea.org\/es\/","name":"IMDEA Networks","description":"IMDEA Networks Multisite","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/networks.imdea.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/networks.imdea.org\/#\/schema\/person\/1dbef87c79bf3d3657cbd4cc6c129e74","name":"Marta Dorado","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/a6b289793dc91627659ec2e23425956502b6bd683dce1548a16e9ea0d40fecfb?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a6b289793dc91627659ec2e23425956502b6bd683dce1548a16e9ea0d40fecfb?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a6b289793dc91627659ec2e23425956502b6bd683dce1548a16e9ea0d40fecfb?s=96&d=mm&r=g","caption":"Marta Dorado"},"url":"https:\/\/networks.imdea.org\/es\/author\/marta-doradoimdea-org\/"}]}},"_links":{"self":[{"href":"https:\/\/networks.imdea.org\/es\/wp-json\/wp\/v2\/posts\/28263","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/networks.imdea.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/networks.imdea.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/networks.imdea.org\/es\/wp-json\/wp\/v2\/users\/145"}],"replies":[{"embeddable":true,"href":"https:\/\/networks.imdea.org\/es\/wp-json\/wp\/v2\/comments?post=28263"}],"version-history":[{"count":2,"href":"https:\/\/networks.imdea.org\/es\/wp-json\/wp\/v2\/posts\/28263\/revisions"}],"predecessor-version":[{"id":28266,"href":"https:\/\/networks.imdea.org\/es\/wp-json\/wp\/v2\/posts\/28263\/revisions\/28266"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/networks.imdea.org\/es\/wp-json\/wp\/v2\/media\/28264"}],"wp:attachment":[{"href":"https:\/\/networks.imdea.org\/es\/wp-json\/wp\/v2\/media?parent=28263"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/networks.imdea.org\/es\/wp-json\/wp\/v2\/categories?post=28263"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/networks.imdea.org\/es\/wp-json\/wp\/v2\/tags?post=28263"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}